{"id":598,"date":"2024-07-10T10:15:05","date_gmt":"2024-07-10T08:15:05","guid":{"rendered":"https:\/\/ub-report.de\/2023\/?p=598"},"modified":"2024-08-28T10:03:04","modified_gmt":"2024-08-28T08:03:04","slug":"users-first-reise-eindruecke-aus-daenemark","status":"publish","type":"post","link":"https:\/\/ub-report.de\/2023\/users-first-reise-eindruecke-aus-daenemark\/","title":{"rendered":"Users First \u2013 Reise-Eindr\u00fccke aus D\u00e4nemark"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1140\" height=\"474\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/header.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1 style=\"color: #d64980!important;\">Users First<\/h1>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2 style=\"color: #d64980!important;\">Reise-Eindr\u00fccke aus D\u00e4nemark<\/h2>\n<p><strong>Eine vierk\u00f6pfige Gruppe der Universit\u00e4tsbibliothek (UB) der TU Berlin und der Fachbibliothek Die Bibliothek Wirtschaft und Management (DBWM) bewarb sich 2019 im Rahmen des TU-Programms Personalmobilit\u00e4t um die Finanzierung eines Fachaustauschs mit d\u00e4nischen Bibliotheken. Nachdem die Pandemie die ersten Planungen \u00fcber den Haufen warf, konnte die dreit\u00e4gige Reise im September 2023 endlich unternommen werden. Die Gruppe setzte sich zusammen aus Dr. Anke Quast (Benutzungsleitung), Martha Ganter (Stabsstelle Innovationsmanagement und Kundenmonitoring) sowie Michaela Jobb und Anne Petit (Bibliotheksleitung und Benutzungsleitung der DBWM).<\/strong><\/p>\n<\/div><\/div><div class=\"w-image us_custom_31230ae7 align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Users-First-\u2013-Reise-Eindruecke-aus-Daenemark-001.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_47291657 has_text_color\"><div class=\"wpb_wrapper\"><p>v.l.n.r.: Martha Ganther, Dr. Anke Quast, Jannik Mulvad, Michaela Jobb und Anne Petit<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Im Zentrum des Interesses standen die Entwicklung von Dienstleistungen unter Ber\u00fccksichtigung der Perspektive von Nutzer*innen, die Interaktion der d\u00e4nischen Bibliotheken mit ihren Zielgruppen, Lernraumgestaltung, Bibliothek als dritter Ort und nicht zuletzt die Vernetzung mit den d\u00e4nischen Kolleg*innen. Dabei war es uns wichtig, neben den wissenschaftlichen Bibliotheken mit verschiedenen fachlichen Ausrichtungen auch die \u00f6ffentlichen in das Besuchsprogramm aufzunehmen.<\/p>\n<p>Die Reise f\u00fchrte uns zu vier Bibliotheken: <a href=\"https:\/\/www.bibliotek.dtu.dk\/en\/\" target=\"_blank\" rel=\"noopener\">Technical University of Dennark (DTU) Library<\/a>, Copenhagen <a href=\"https:\/\/www.cbs.dk\/en\/library\" target=\"_blank\" rel=\"noopener\">Business School (CBS) Library<\/a>, <a href=\"https:\/\/library.au.dk\/en\/\" target=\"_blank\" rel=\"noopener\">Aarhus University Library<\/a>, <a href=\"https:\/\/www.dokk1.dk\/english\" target=\"_blank\" rel=\"noopener\">Dokk1 Aarhus<\/a>, <a href=\"https:\/\/kub.ku.dk\/english\/libraries\/samf\/\" target=\"_blank\" rel=\"noopener\">Copenhagen University Library\/Faculty Library of Social Sciences<\/a>. Die Kolleg*innen dort gew\u00e4hrten uns Einblicke in ihren Arbeitsalltag, bei dem die Nutzer*innen im Fokus stehen. Das spiegelt sich nicht nur in strategischen Entscheidungen, sondern ebenso im t\u00e4glichen Arbeitsleben wider und findet sich u.a. im Motto der \u00f6ffentlichen Bibliothek in Aarhus Dokk1: \u201eUsers First&#8220;. Hier wurde uns besonders deutlich, welche Auswirkungen dieser Fokus f\u00fcr s\u00e4mtliche Arbeitsabl\u00e4ufe und auch die Raumgestaltung der Bibliothek hat. Der Gro\u00dfteil der T\u00e4tigkeiten der Mitarbeiter*innen findet dort im \u00f6ffentlichen Bereich in Interaktion mit den Nutzer*innen statt, w\u00e4hrend der B\u00fcroraum f\u00fcr interne Meetings und konzeptionelle Arbeit genutzt wird. Die Teammitglieder, einschlie\u00dflich der Direktorin, teilen sich ein gemeinschaftliches Gro\u00dfraumb\u00fcro, das an ein Start-Up erinnert. Diese offene B\u00fcrostruktur beg\u00fcnstigt kurze Abstimmungswege, unterst\u00fctzt die Zusammenarbeit und schafft eine dynamische Arbeitsatmosph\u00e4re. Auch an der DTU-Bibliothek findet sich diese offene B\u00fcrostruktur, die informelle und spontane Zusammenk\u00fcnfte der Mitarbeiter*innen an Stehtischen und Workbays in Bereichen vor den B\u00fcros f\u00f6rdert.<\/p>\n<p>Die Universit\u00e4tsbibliothek in Aarhus beeindruckt trotz ihres eher konventionellen Erscheinungsbilds mit ihrer dezidierten aktiven Einbeziehung ihrer Nutzer*innen bei Umgestaltungsma\u00dfnahmen, was zu einem au\u00dfergew\u00f6hnlichen &#8222;Library Garden&#8220; f\u00fchrte \u2013 einem sehr sch\u00f6nen, offenen und hellen Bereich mit Pflanzen und Sitzm\u00f6glichkeiten.<\/p>\n<p>Besonders aufgefallen sind uns die Erholungs- und Entspannungsbereiche in allen Bibliotheken. Dabei haben uns die Massagesessel und H\u00e4ngematten in mit Vorh\u00e4ngen abgeschirmten Bereichen sowie der Glasraum mit einer Tischtennisplatte und einem Boxsack an der Universit\u00e4tsbibliothek in Aarhus besonders gut gefallen. An der DTU waren es die Gaming-M\u00f6glichkeiten mit Playstation und Monitor\u00a0 sowie verschiedenste andere Maker-Space-Szenarien wie DIY-N\u00e4hstudios.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ein Standardangebot aller besuchten Bibliotheken war die M\u00f6glichkeit f\u00fcr Besucher*innen sich warme Speisen zu kochen oder aufzuw\u00e4rmen, Tee und Kaffee zuzubereiten und die Bereitstellung von Wasserspendern, um Wasserflaschen aufzuf\u00fcllen.<\/p>\n<p>Urspr\u00fcnglicher Ausl\u00f6ser f\u00fcr die Idee den Austausch mit d\u00e4nischen Bibliotheken zu suchen, waren die zahlreichen Aktivit\u00e4ten der DTU Library im Feld User Experience. Auf diesem Gebiet war diese Bibliothek bereits vor der Pandemie sehr aktiv und hat ihr Engagement im Jahr 2022 mit neuem Schwung mit der Neubildung eines UX-Teams wieder aufgenommen. Das Leitprinzip der Arbeitsgruppe lautet: &#8222;Every time we want to change, we go out and test it.&#8220; Ein konkretes Beispiel daf\u00fcr ist die partizipative Gestaltung des Frontends der Digitalisierungsplattform, die zusammen mit Nutzer*innen ausprobiert und basierend auf deren R\u00fcckmeldungen optimiert wurde. Die DTU Library sieht sich nicht mehr prim\u00e4r als traditionelle Bibliothek mit herk\u00f6mmlichen Angeboten wie Leses\u00e4len oder physischen B\u00fcchern. Stattdessen wird konsequent auf die Erf\u00fcllung von Bedarfen eingegangen.<\/p>\n<p>Trotz der an allen d\u00e4nischen Bibliotheken stark ausgepr\u00e4gten Nutzerzentrierung wird an der CBS, der DTU und Det Kongelige Bibliotek jeweils nur eine Informationstheke besetzt. Die Pr\u00e4misse &#8222;Users First&#8220; steht nicht im Widerspruch zur Abwesenheit von Bibliothekspersonal in den Benutzungsbereichen, wie beispielsweise bei der Besetzung der Informationstheke. Stattdessen wird auf vielf\u00e4ltige Weise aktiv die Interaktion mit den Nutzer*innen gesucht.<\/p>\n<p>Was haben wir von der Reise f\u00fcr unsere Bibliotheken als Anregung mitgenommen? Der Fachaufenthalt in D\u00e4nemark gew\u00e4hrte tiefe Einblicke in die Praxis nutzerzentrierter Bibliotheksarbeit. Gefallen haben uns die einfachen, niedrigschwelligen Interaktionsangebote, z.B. die Idee der CBS, im Eingangsbereich eine Weltkarte aufzustellen und die Besucher*innen aufzufordern, ihren Herkunftsort zu markieren. Die Verteilung der F\u00e4hnchen auf dem Globus visualisiert die geografische und kulturelle Vielfalt der Studierenden sehr eindr\u00fccklich.<\/p>\n<p>Die gewonnenen Erkenntnisse werden wir aktiv nutzen, um das Erlebnis unserer Nutzer*innen in den Bibliotheken der TU Berlin zu optimieren.<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_af6a9b6a\"><div class=\"wpb_wrapper\"><div class=\"w-gallery fit_cover wp_gallery type_grid action_popup_image count_11\" style=\"--columns:4;--items-gap:8px;--item-aspect-ratio:1;\"><div class=\"w-gallery-list\"><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-014.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-014\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-014.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-014\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-009.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-009\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-009.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-009\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-010.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-010\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-010.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-010\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"84\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-012.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-012\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-012.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-012\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-011.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-011\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-011.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-011\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-006.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-006\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-006.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-006\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-004.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-004\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-004.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-004\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-007.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-007\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-007.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-007\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-008.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-008\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-008.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-008\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"84\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-002.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-002\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-002.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-002\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-001.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Personalmobilit\u00e4t-1200px-300dpi-001\" href=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Personalmobilitaet-1200px-300dpi-001.jpg\" title=\"Personalmobilit\u00e4t-1200px-300dpi-001\"><\/a><\/div><\/div><\/div>\n<\/div><\/div><style>#mdp-lottier-box-05fb2947e6aa55cda9defa4d741e7834 .mdp-lottier-svg .mdp-lottier-player{ width: 100%; }#mdp-lottier-box-05fb2947e6aa55cda9defa4d741e7834 .mdp-lottier-svg { justify-content: flex-start; }<\/style><!-- Start Lottier for WPBakery WordPress Plugin --><div id=\"mdp-lottier-box-05fb2947e6aa55cda9defa4d741e7834\" class=\"mdp-lottier-box\">\n\t    <div class=\"mdp-lottier-svg\">\n\t\t    <div class=\"mdp-lottier-player\"\n                 data-id=\"05fb2947e6aa55cda9defa4d741e7834\"\n                 data-finish-before-pause=\"\"\n\t\t         data-autoplay=\"visible\"\n\t\t         data-speed=\"1\"\n\t\t         data-loop=\"false\"\n\t\t         data-controls=\"false\"\n\t\t         data-mode=\"normal\"\n\t\t    >\n\t\t\t    <!--suppress HtmlUnknownTag -->\n\t\t\t                        <lottie-player id=\"mdp-lottier-05fb2947e6aa55cda9defa4d741e7834\"\n                                   class=\"mdp-lottier-animation \"\n                                   src='https:\/\/ub-report.de\/wp-content\/uploads\/2024\/08\/trennstrich-02.json'><\/lottie-player>\n                \t\t    <\/div>\n\t    <\/div>\n\n\t    \n\t    \t    <\/div>\n\t    <!-- End Lottier for WPBakery WordPress Plugin -->\n\n\t    <div class=\"g-cols wpb_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image authorPic align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Dr-Anke-Quast-1.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_4fb2abd2 bgUrheber has_text_color\"><div class=\"wpb_wrapper\"><p>\u00a9 UB TU Berlin, C. Giakoumelou<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Dr. Anke Quast<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image authorPic align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/MichaelaJobb-thumb.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/MichaelaJobb-thumb.jpg 300w, https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/MichaelaJobb-thumb-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_4fb2abd2 bgUrheber has_text_color\"><div class=\"wpb_wrapper\"><p>\u00a9 Michael Setzpfandt<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Michaela Jobb<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image authorPic align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/AnnePetit-thumb.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/AnnePetit-thumb.jpg 300w, https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/AnnePetit-thumb-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_4fb2abd2 bgUrheber has_text_color\"><div class=\"wpb_wrapper\"><p>\u00a9 Michael Setzpfandt<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Anne Petit<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-post-elm post_navigation layout_sided inv_false\"><a class=\"post_navigation-item order_first to_prev\" href=\"https:\/\/ub-report.de\/2023\/wir-sind-oat23\/\" title=\"Wir sind #OAT23!\"><div class=\"post_navigation-item-img\"><img decoding=\"async\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/thumb-OAT.png\" loading=\"lazy\" alt=\"\" width=\"150\" height=\"150\"><\/div><div class=\"post_navigation-item-arrow\"><\/div><div class=\"post_navigation-item-title\"><span>Wir sind #OAT23!<\/span><\/div><\/a><a class=\"post_navigation-item order_second to_next\" href=\"https:\/\/ub-report.de\/2023\/gemeinsam-mehr-service-berlinup-feierlich-eroeffnet\/\" title=\"Gemeinsam mehr Service &#8211; BerlinUP feierlich er\u00f6ffnet\"><div class=\"post_navigation-item-img\"><img decoding=\"async\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/07\/Thumb-BerlinUP.png\" loading=\"lazy\" alt=\"\" width=\"150\" height=\"150\"><\/div><div class=\"post_navigation-item-arrow\"><\/div><div class=\"post_navigation-item-title\"><span>Gemeinsam mehr Service &#8211; BerlinUP feierlich er\u00f6ffnet<\/span><\/div><\/a><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Users First Reise-Eindr\u00fccke aus D\u00e4nemark Eine vierk\u00f6pfige Gruppe der Universit\u00e4tsbibliothek (UB) der TU Berlin und der Fachbibliothek Die Bibliothek Wirtschaft und Management (DBWM) bewarb sich 2019 im Rahmen des TU-Programms Personalmobilit\u00e4t um die Finanzierung eines Fachaustauschs mit d\u00e4nischen Bibliotheken. Nachdem die Pandemie die ersten Planungen \u00fcber den Haufen warf, konnte die dreit\u00e4gige Reise im September...","protected":false},"author":3,"featured_media":621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/posts\/598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/comments?post=598"}],"version-history":[{"count":0,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/posts\/598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/media\/621"}],"wp:attachment":[{"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/media?parent=598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/categories?post=598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/tags?post=598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}