{"id":458,"date":"2024-06-17T08:44:42","date_gmt":"2024-06-17T06:44:42","guid":{"rendered":"https:\/\/ub-report.de\/2023\/?p=458"},"modified":"2024-08-28T10:01:13","modified_gmt":"2024-08-28T08:01:13","slug":"neue-automaten-in-der-bib","status":"publish","type":"post","link":"https:\/\/ub-report.de\/2023\/neue-automaten-in-der-bib\/","title":{"rendered":"Neue Automaten in der Bib"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1140\" height=\"474\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/header.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1 style=\"color: #98e503!important;\">Neue Automaten in der Bib<\/h1>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Unsere Ausleih- und R\u00fcckgabeautomaten waren wirklich in die Jahre gekommen. Oft waren sie reparaturbed\u00fcrftig und fielen wochenlang aus. Das erzeugte Frust und Missstimmung sowohl bei unseren Nutzer*innen als auch im Team. Die veraltete Technologie verursachte einen erheblichen Personalaufwand und hohe Kosten f\u00fcr Notfallreparaturen. Die Bibliotheken der TU Berlin und der UdK Berlin suchten folglich nach modernen, bedienungsfreundlichen und ergonomischen Selbstbedienungsger\u00e4ten, die den aktuellen technischen Standards entsprechen und innovative Nutzungsm\u00f6glichkeiten bieten.<\/strong><\/p>\n<p>Was ist nun \u201eState of the Art\u201c? Welche aktuellen Herausforderungen gibt es? Welche Voraussetzungen m\u00fcssen erf\u00fcllt werden? So \u00e4hnlich beginnt das Vergabeverfahren und wir erstellen eine Leistungsbeschreibung.<\/p>\n<p>W\u00e4hrend der Vorbereitungsphase wurden zwei Teilprojekte identifiziert:<\/p>\n<p><strong>1. RFID-Sicherung der Best\u00e4nde<\/strong><br \/>\nDie Entscheidung f\u00e4llt gegen eine kostspielige hybride L\u00f6sung f\u00fcr die Sicherheitsgates und f\u00fcr die Ausstattung der Best\u00e4nde, die bis 2023 noch ohne RFID-Sicherung in den Regalen stehen konnten.<\/p>\n<p><strong>2. Umgestaltung des Bereichs Foyer \u2013 Leihstelle im Erdgeschoss<\/strong><br \/>\nDas Aufstellen von neuen Automaten f\u00fchrt letztendlich auch zu baulichen Anpassungen. Der Einsatz von Bauabteilung und IT-Abteilung ist also unerl\u00e4sslich und dient dann auch der Frage: Wie optimieren wir baulich die Arbeitsprozesse f\u00fcr Mitarbeiter*innen und Nutzer*innen?<\/p>\n<p>Welche Funktionalit\u00e4ten bringen die Neuen mit?<\/p>\n<ul>\n<li>Ausleihautomaten mit Bezahlfunktion, Lesem\u00f6glichkeit der UdK-Campuscard, H\u00f6henverstellbarkeit und die Stapelverbuchung<\/li>\n<li>Buchr\u00fcckgabeautomat mit Sortierstra\u00dfe, Buchcontainern (Bins), 90 Grad-Drehung (f\u00fcr die Umgestaltung der Leihstelle), Mitarbeiterr\u00fcckgabe im internen Bereich<\/li>\n<li>Sicherheitsgates (RFID) mit Statistikfunktion f\u00fcr die Universit\u00e4tsbibliotheken von TU und UdK, sowie f\u00fcr die Bereichsbibliotheken der TU<\/li>\n<li>RFID-Workstations f\u00fcr Stapelverbuchung durch die Mitarbeiter*innen an der Theke<\/li>\n<\/ul>\n<p>Das dritte Teilprojekt im Kontext der neuen Automaten hat seinen Ursprung in der Entscheidung der UdK Berlin, sich am <a href=\"https:\/\/campuscard.berlin\/\" target=\"_blank\" rel=\"noopener\">Berliner Campuscard-Projekt<\/a> zu beteiligen. In diesem Verbundprojekt ist angelegt, die Campuscard auch mit der Funktionalit\u00e4t \u201eBibliotheksausweis\u201c auszustatten.<\/p>\n<p>Der Landesverband Berlin des Deutschen Bibliotheksverbandes besch\u00e4ftigt sich seit 2019 mit der Fragestellung: \u201eWas wollen Nutzer*innen?\u201c. Die Besch\u00e4ftigung mit dem Thema f\u00fchrt 2021 zur Beauftragung eines Gutachtens bei Herrn Dr. Vo\u00df: \u201e<a href=\"https:\/\/www.bibliotheksverband.de\/gemeinsamer-bibliotheksausweis-fuer-berlin\" target=\"_blank\" rel=\"noopener\">Ein gemeinsamer Bibliotheksausweis f\u00fcr Berlin<\/a>\u201c.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ziel des dritten Teilprojekts war, die technischen Voraussetzungen zu schaffen, um die Campuscard im gemeinsamen Geb\u00e4ude, aber auch in den Bereichs- und Fachbibliotheken der TU Berlin zum Einsatz bringen zu k\u00f6nnen. Es diente gleichzeitig als Pilotprojekt f\u00fcr die Anerkennung der Bibliotheksausweise in drei weiteren Berliner Bibliotheken (FU, HU und Charit\u00e9). Starttermin f\u00fcr den Einsatz der UdK-Campuscard als Bibliotheksausweis war der 01.10.2023. Im letzten Quartal 2023 haben rund 500 UdK-Studierende ihre Karte \u201efreischalten\u201c lassen.<\/p>\n<\/div><\/div><div class=\"w-image us_custom_99817634 align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"540\" height=\"405\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/neu-neu-neu-Automaten.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Gemeinsam haben wir ein gro\u00dfes Projekt erfolgreich abgeschlossen und alle Herausforderungen gemeistert. Dazu geh\u00f6rte auch die komplexe Kommunikation zwischen den zahlreichen Beteiligten. Um nur Einige zu nennen: Mitarbeiter*innen der beiden Bibliotheken, alle Beteiligten beim Vergabeverfahren, Bauabteilung der TU Berlin, die IT-Abteilungen der Bibliotheken sowie die verschiedenen Firmen und ihre Techniker*innen.<\/p>\n<p>\u201eDie Neuen\u201c haben sich etabliert und sie sind uns ans Herz gewachsen, so kommentiert Anja Hirche, Leiterin der Leihstelle f\u00fcr die Universit\u00e4tsbibliothek der TU Berlin.<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_9dd2169b\"><div class=\"wpb_wrapper\"><p>\u201e<em>Die Kolleg*innen in der Leihstelle haben es beim Verbuchen der Medien jetzt viel leichter als fr\u00fcher, weil Medien, auch als Stapel, nur noch auf eine RFID-Fl\u00e4che gelegt werden m\u00fcssen.<\/em>&#8222;<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Die Ausleih- und R\u00fcckgabe-Automaten sind in der Nutzung f\u00fcr die Kund*innen viel intuitiver und haben au\u00dferdem sch\u00f6ne, individuelle Namen erhalten, die das Ergebnis einer Befragung und Social-Media-Kampagne unter Mitarbeitenden und Kund*innen waren:<\/p>\n<p><strong>Herzlich Willkommen Mulder, Scully, Renate, Waffel und Bob.<\/strong><\/p>\n<\/div><\/div><div class=\"w-video us_custom_0f8f44b7 align_none has_iframe\" style=\"aspect-ratio:4 \/ 3;\"><div class=\"w-video-h\"><iframe title=\"Youtube video player\" src=\"\/\/www.youtube.com\/embed\/c0mFhAmMUIM?autoplay=0&controls=1&origin=https:\/\/ub-report.de\/2023&loop=0&mute=0\" allowfullscreen=\"1\" loading=\"lazy\"><\/iframe><\/div><\/div><div class=\"wpb_text_column us_custom_5ad3a503 has_text_color\"><div class=\"wpb_wrapper\"><p>Hinweis: Beim Laden des Thumbnails werden keine Cookies gesetzt. Erst beim Abspielen des Videos werden personenbezogene Daten an YouTube \u00fcbermittelt.<\/p>\n<\/div><\/div><style>#mdp-lottier-box-05fb2947e6aa55cda9defa4d741e7834 .mdp-lottier-svg .mdp-lottier-player{ width: 100%; }#mdp-lottier-box-05fb2947e6aa55cda9defa4d741e7834 .mdp-lottier-svg { justify-content: flex-start; }<\/style><!-- Start Lottier for WPBakery WordPress Plugin --><div id=\"mdp-lottier-box-05fb2947e6aa55cda9defa4d741e7834\" class=\"mdp-lottier-box\">\n\t    <div class=\"mdp-lottier-svg\">\n\t\t    <div class=\"mdp-lottier-player\"\n                 data-id=\"05fb2947e6aa55cda9defa4d741e7834\"\n                 data-finish-before-pause=\"\"\n\t\t         data-autoplay=\"visible\"\n\t\t         data-speed=\"1\"\n\t\t         data-loop=\"false\"\n\t\t         data-controls=\"false\"\n\t\t         data-mode=\"normal\"\n\t\t    >\n\t\t\t    <!--suppress HtmlUnknownTag -->\n\t\t\t                        <lottie-player id=\"mdp-lottier-05fb2947e6aa55cda9defa4d741e7834\"\n                                   class=\"mdp-lottier-animation \"\n                                   src='https:\/\/ub-report.de\/wp-content\/uploads\/2024\/08\/trennstrich-02.json'><\/lottie-player>\n                \t\t    <\/div>\n\t    <\/div>\n\n\t    \n\t    \t    <\/div>\n\t    <!-- End Lottier for WPBakery WordPress Plugin -->\n\n\t    <div class=\"g-cols wpb_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image authorPic align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/Andrea-Zeyns_UB-UdK-Berlin_by_Jens-Ahner.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/Andrea-Zeyns_UB-UdK-Berlin_by_Jens-Ahner.png 300w, https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/Andrea-Zeyns_UB-UdK-Berlin_by_Jens-Ahner-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_4fb2abd2 bgUrheber has_text_color\"><div class=\"wpb_wrapper\"><p>\u00a9 J. Ahner<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Andrea Zeyns<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image authorPic align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/Michael-Jurk-01.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_4fb2abd2 bgUrheber has_text_color\"><div class=\"wpb_wrapper\"><p>\u00a9 Privat<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Michael Jurk<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-post-elm post_navigation layout_sided inv_false\"><a class=\"post_navigation-item order_first to_prev\" href=\"https:\/\/ub-report.de\/2023\/lesen-und-publizieren-bis-2028\/\" title=\"Lesen und Publizieren bis 2028\"><div class=\"post_navigation-item-img\"><img decoding=\"async\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/thumb-bibhop.png\" loading=\"lazy\" alt=\"\" width=\"150\" height=\"150\"><\/div><div class=\"post_navigation-item-arrow\"><\/div><div class=\"post_navigation-item-title\"><span>Lesen und Publizieren bis 2028<\/span><\/div><\/a><a class=\"post_navigation-item order_second to_next\" href=\"https:\/\/ub-report.de\/2023\/regalplanung-reloaded\/\" title=\"Regalplanung reloaded\"><div class=\"post_navigation-item-img\"><img decoding=\"async\" src=\"https:\/\/ub-report.de\/2023\/wp-content\/uploads\/2024\/06\/thumb-regalplanung03.png\" loading=\"lazy\" alt=\"\" width=\"150\" height=\"150\"><\/div><div class=\"post_navigation-item-arrow\"><\/div><div class=\"post_navigation-item-title\"><span>Regalplanung reloaded<\/span><\/div><\/a><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Neue Automaten in der Bib Unsere Ausleih- und R\u00fcckgabeautomaten waren wirklich in die Jahre gekommen. Oft waren sie reparaturbed\u00fcrftig und fielen wochenlang aus. Das erzeugte Frust und Missstimmung sowohl bei unseren Nutzer*innen als auch im Team. Die veraltete Technologie verursachte einen erheblichen Personalaufwand und hohe Kosten f\u00fcr Notfallreparaturen. Die Bibliotheken der TU Berlin und der...","protected":false},"author":3,"featured_media":465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/posts\/458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/comments?post=458"}],"version-history":[{"count":0,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/posts\/458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/media\/465"}],"wp:attachment":[{"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/media?parent=458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/categories?post=458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ub-report.de\/2023\/wp-json\/wp\/v2\/tags?post=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}